









{"id":11309,"date":"2019-09-07T22:42:54","date_gmt":"2019-09-07T20:42:54","guid":{"rendered":"http:\/\/www.polovalboite.gov.it\/cms\/?p=11309"},"modified":"2019-09-07T22:42:57","modified_gmt":"2019-09-07T20:42:57","slug":"convocazione-centralizzata-personale-docente","status":"publish","type":"post","link":"http:\/\/polovalboite.edu.it\/convocazione-centralizzata-personale-docente\/","title":{"rendered":"Convocazione centralizzata personale docente"},"content":{"rendered":"\n<p>Comunicato &#8211; <a href=\"http:\/\/www.polovalboite.edu.it\/cms\/convocazione-personale-docente-definitiva-signed\/\">Convocazione centralizzata personale docente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comunicato &#8211; Convocazione centralizzata personale docente<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"_links":{"self":[{"href":"http:\/\/polovalboite.edu.it\/wp-json\/wp\/v2\/posts\/11309"}],"collection":[{"href":"http:\/\/polovalboite.edu.it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/polovalboite.edu.it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/polovalboite.edu.it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/polovalboite.edu.it\/wp-json\/wp\/v2\/comments?post=11309"}],"version-history":[{"count":1,"href":"http:\/\/polovalboite.edu.it\/wp-json\/wp\/v2\/posts\/11309\/revisions"}],"predecessor-version":[{"id":11311,"href":"http:\/\/polovalboite.edu.it\/wp-json\/wp\/v2\/posts\/11309\/revisions\/11311"}],"wp:attachment":[{"href":"http:\/\/polovalboite.edu.it\/wp-json\/wp\/v2\/media?parent=11309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/polovalboite.edu.it\/wp-json\/wp\/v2\/categories?post=11309"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/polovalboite.edu.it\/wp-json\/wp\/v2\/tags?post=11309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}